{"id":286,"date":"2016-08-28T05:02:26","date_gmt":"2016-08-28T03:02:26","guid":{"rendered":"http:\/\/hofacker-webdesign.de\/projekte\/getraenkeparadies\/2016\/08\/28\/veranstaltungen\/"},"modified":"2022-05-04T08:28:53","modified_gmt":"2022-05-04T06:28:53","slug":"veranstaltungen","status":"publish","type":"post","link":"https:\/\/hofacker-webdesign.de\/getraenkeparadies\/veranstaltungen\/","title":{"rendered":"Veranstaltungen"},"content":{"rendered":"<div id=\"c2393\" class=\"frame frame-default frame-type-header frame-layout-0\">\n<header>\n<h1 class=\"\">Bierdorf in Pfedelbach<\/h1>\n<\/header>\n<\/div>\n<div class=\"row\">\n<div class=\"col-md-5\">\n<div id=\"c2395\" class=\"frame frame-default frame-type-textpic frame-layout-0\">\n<header>\n<h1 class=\"\">Das Bierdorf findet vom 09.-10. September 2022 statt<\/h1>\n<\/header>\n<div class=\"ce-textpic ce-center ce-above\">\n<div class=\"ce-bodytext\">\n<p>Der Rathausvorplatz, der Rathausparkplatz und die angrenzende Hauptstra\u00dfe bilden das Festgel\u00e4nde f\u00fcr das Pfedelbacher Bierdorf. Das alle drei Jahre stattfindende Bierdorf mitten in einer Weinregion begeistert nicht nur wegen der Geselligkeit, sondern auch wegen der seltenen Gelegenheit, unter rund 30 Biermarken plus Biermixgetr\u00e4nken w\u00e4hlen zu k\u00f6nnen.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-658\" src=\"http:\/\/hofacker-webdesign.de\/projekte\/getraenkeparadies\/wp-content\/uploads\/2016\/08\/2022-bierdorf-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/hofacker-webdesign.de\/getraenkeparadies\/wp-content\/uploads\/2016\/08\/2022-bierdorf-300x200.jpg 300w, https:\/\/hofacker-webdesign.de\/getraenkeparadies\/wp-content\/uploads\/2016\/08\/2022-bierdorf-1024x683.jpg 1024w, https:\/\/hofacker-webdesign.de\/getraenkeparadies\/wp-content\/uploads\/2016\/08\/2022-bierdorf-768x512.jpg 768w, https:\/\/hofacker-webdesign.de\/getraenkeparadies\/wp-content\/uploads\/2016\/08\/2022-bierdorf.jpg 1140w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Bierdorf in Pfedelbach Das Bierdorf findet vom 09.-10. September 2022 statt Der Rathausvorplatz, der Rathausparkplatz und die angrenzende Hauptstra\u00dfe bilden das Festgel\u00e4nde f\u00fcr das Pfedelbacher Bierdorf. Das alle drei Jahre stattfindende Bierdorf mitten in einer Weinregion begeistert nicht nur wegen der Geselligkeit, sondern auch wegen der seltenen Gelegenheit, unter rund 30 Biermarken plus Biermixgetr\u00e4nken w\u00e4hlen<span class=\"read_more_area\"><a class=\"read-more\" href=\"https:\/\/hofacker-webdesign.de\/getraenkeparadies\/veranstaltungen\/\"> Continue Reading <\/a><\/span><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[59],"tags":[],"class_list":["post-286","post","type-post","status-publish","format-standard","hentry","category-veranstaltungen-veranstaltungen"],"_links":{"self":[{"href":"https:\/\/hofacker-webdesign.de\/getraenkeparadies\/wp-json\/wp\/v2\/posts\/286","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hofacker-webdesign.de\/getraenkeparadies\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hofacker-webdesign.de\/getraenkeparadies\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hofacker-webdesign.de\/getraenkeparadies\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/hofacker-webdesign.de\/getraenkeparadies\/wp-json\/wp\/v2\/comments?post=286"}],"version-history":[{"count":4,"href":"https:\/\/hofacker-webdesign.de\/getraenkeparadies\/wp-json\/wp\/v2\/posts\/286\/revisions"}],"predecessor-version":[{"id":659,"href":"https:\/\/hofacker-webdesign.de\/getraenkeparadies\/wp-json\/wp\/v2\/posts\/286\/revisions\/659"}],"wp:attachment":[{"href":"https:\/\/hofacker-webdesign.de\/getraenkeparadies\/wp-json\/wp\/v2\/media?parent=286"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hofacker-webdesign.de\/getraenkeparadies\/wp-json\/wp\/v2\/categories?post=286"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hofacker-webdesign.de\/getraenkeparadies\/wp-json\/wp\/v2\/tags?post=286"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}